{"id":4231,"date":"2021-10-19T13:37:48","date_gmt":"2021-10-19T11:37:48","guid":{"rendered":"https:\/\/pizzastick.es\/?p=4231"},"modified":"2022-01-25T16:29:26","modified_gmt":"2022-01-25T14:29:26","slug":"pedido-online-pizza-stick-cerdanya","status":"publish","type":"post","link":"https:\/\/pizzastick.es\/ca\/pedido-online-pizza-stick-cerdanya\/","title":{"rendered":"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic!"},"content":{"rendered":"<p><b>\u00a1Ei amigo de Pizza Stick! Te escuchamos y por fin tenemos novedades.<\/b><\/p>\n<p><b>Queremos estar a tu lado y mejorar nuestros servicios, por eso hemos creado \u00abPIDE ONLINE\u00bb.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como sabemos que cuando el volumen de trabajo \u00e9s grande, es dif\u00edcil de contactar con nosotros: hemos querido poner-te-lo f\u00e1cil y simplificar el proceso para hacer tu pedido online, ahora lo tienes a un clic:<\/span><\/p>\n<p><a href=\"https:\/\/pizzastick.es\/ca\/pedidos\/#\/where\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4264 size-medium\" src=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PIDE-ONLINE-PIZZA-STICK-300x106.png\" alt=\"\" width=\"300\" height=\"106\" srcset=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PIDE-ONLINE-PIZZA-STICK-300x106.png 300w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PIDE-ONLINE-PIZZA-STICK-768x271.png 768w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PIDE-ONLINE-PIZZA-STICK-700x247.png 700w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PIDE-ONLINE-PIZZA-STICK.png 773w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Y como premio a tu confianza en Pizza Stick: ahorra un 10% en tu primer pedido\u00a0<\/span><a href=\"https:\/\/pizzastick.es\/ca\/pedidos\/#\/where\"><span style=\"font-weight: 400;\">a trav\u00e9s de nuestra web pizzastick.es o de nuestra app.<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><em><span style=\"font-weight: 400;\">*El servicio PIDE ONLINE esta disponible en el mismo horario de nuestra pizzer\u00eda. <\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400;\">* Cualquier consulta o incidencia no dudes en llamar a tu Pizza Stick.<\/span><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><b><\/b><a href=\"https:\/\/pizzastick.es\/ca\/pedidos\/#\/where\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4246\" src=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PizzaStick_GC-1024x576.jpg\" alt=\"\" width=\"752\" height=\"423\" srcset=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PizzaStick_GC-1024x576.jpg 1024w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PizzaStick_GC-300x169.jpg 300w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PizzaStick_GC-768x432.jpg 768w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PizzaStick_GC-700x394.jpg 700w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PizzaStick_GC-539x303.jpg 539w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PizzaStick_GC.jpg 1080w\" sizes=\"auto, (max-width: 752px) 100vw, 752px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><b>Sabemos que tu tiempo vale PIZZA y que la familia es el motor de la vida&#8230; por eso te proponemos que pidas tu <em>comilona<\/em> online en un <em>pim pam<\/em> y aproveches tu tiempo: comparte tu momento redondo \u00a1lleno de pizzas, sonrisas y an\u00e9cdotas!<\/b><b><\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\" aria-checked=\"false\"><span style=\"font-weight: 400;\">Hemos invertido en una nueva tecnolog\u00eda que te simplifica el hacer tu comanda online.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\" aria-checked=\"false\"><span style=\"font-weight: 400;\">Para que tu puedas dedicar tu tiempo a lo que quieras.\u00a0<\/span><\/li>\n<li aria-level=\"1\" aria-checked=\"false\">Como ya sabes, nuestro equipo es importante para nosotros y con esta novedad, mejoramos tambi\u00e9n la organizaci\u00f3n interna, nos ayuda a hacer m\u00e1s f\u00e1cil el trabajo de nuestros pizzaiolos. Un win win!<\/li>\n<li aria-level=\"1\" aria-checked=\"false\">Nos hemos digitalizado siguiendo nuestro objetivo del a\u00f1o: SIMPLIFICAR.<\/li>\n<\/ul>\n<h2><\/h2>\n<h2><span style=\"font-weight: 400;\">VIVE UN MOMENTO REDONDO CON LOS TUYOS \u00a1EN UN CLIC!<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Puedes hacer tu pedido online a trav\u00e9s de <a href=\"https:\/\/pizzastick.es\/ca\/pedidos\/#\/where\">pizzastick.es o de la app Pizza Stick.<\/a><\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Clica <\/span><a href=\"https:\/\/pizzastick.es\/ca\/pedidos\/\"><span style=\"font-weight: 400;\">https:\/\/pizzastick.es\/pedidos\/<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Decide si te lo entregamos a domicilio o vienes a tu pizzeria a recoger. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Elige tu Pizza Stick m\u00e1s cercana a ti.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Haz tu pedido online \u00a1y ponte c\u00f3mod@!<\/span><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4268 size-full\" src=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PEDIDO-ONLINE-CERDANYA-PIZZERIA-PIZZASTICK.png\" alt=\"\" width=\"843\" height=\"90\" srcset=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PEDIDO-ONLINE-CERDANYA-PIZZERIA-PIZZASTICK.png 843w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PEDIDO-ONLINE-CERDANYA-PIZZERIA-PIZZASTICK-300x32.png 300w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PEDIDO-ONLINE-CERDANYA-PIZZERIA-PIZZASTICK-768x82.png 768w, https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/PEDIDO-ONLINE-CERDANYA-PIZZERIA-PIZZASTICK-700x75.png 700w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pizza Stick te ofrece ensaladas, pizzas, bebidas y postres para que te lleves a casa. <a href=\"https:\/\/pizzastick.es\/ca\/pedidos\/#\/where\">Haz tu pedido online\u00a0o b\u00e1jate nuestra app<\/a> y degusta tu momento!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ah \u00bfy sabes qu\u00e9? <strong><span style=\"color: #800000;\">Ahorra un 10% en tu primer pedido.<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u00a1Enam\u00f3rate de tu #momentoPizzaStick!<\/span><\/p>\n<p><b><span style=\"font-weight: 400;\">Mejoramos la atenci\u00f3n al cliente poniendo la tecnolog\u00eda a tu favor: \u00a1ya puedes pedir online!<\/span><\/b><\/p>\n<p><b><span style=\"font-weight: 400;\">Gracias #PizzaLover, no dudes en compartir con nosotros tu #momentopizza y etiqu\u00e9tanos: @pizzeriapizzastick, lo compartiremos con todos nuestros Pizza Stick followers.<\/span><\/b><\/p>\n<h2><b>Clic, clic,&#8230; \u00a1\u00f1am, \u00f1am!<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><em><span style=\"font-weight: 400;\">*El servicio PIDE ONLINE esta disponible en el mismo horario de nuestra pizzer\u00eda. <\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400;\">* Cualquier consulta o incidencia no dudes en llamar a tu Pizza Stick.<\/span><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Ei amigo de Pizza Stick! Te escuchamos y por fin tenemos novedades. Queremos estar a tu lado y mejorar nuestros servicios, por eso hemos creado \u00abPIDE ONLINE\u00bb. &nbsp; Como sabemos que cuando el volumen de trabajo \u00e9s grande, es dif\u00edcil de contactar con nosotros: hemos&#8230;<\/p>","protected":false},"author":3,"featured_media":4250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[91,117,116,115,93,118],"class_list":["post-4231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-cerdanya-2","tag-comanda-online","tag-delivery","tag-demana-online","tag-pizzeria-2","tag-shop-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activamos el pedido online, \u00a1conecta con nosotros en un solo clic! - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes<\/title>\n<meta name=\"description\" content=\"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pizzastick.es\/ca\/pedido-online-pizza-stick-cerdanya\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic! - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\" \/>\n<meta property=\"og:description\" content=\"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pizzastick.es\/ca\/pedido-online-pizza-stick-cerdanya\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pizzeriapizzastick\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-19T11:37:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-25T14:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/demana_online_stick.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pizza_stick_\" \/>\n<meta name=\"twitter:site\" content=\"@pizza_stick_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/\"},\"author\":{\"name\":\"Andrea\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/person\\\/c164ec506c453162653fb0ffe1c16cce\"},\"headline\":\"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic!\",\"datePublished\":\"2021-10-19T11:37:48+00:00\",\"dateModified\":\"2022-01-25T14:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/\"},\"wordCount\":426,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/demana_online_stick.jpg\",\"keywords\":[\"Cerdanya\",\"Comanda Online\",\"Delivery\",\"Demana Online\",\"Pizzer\u00eda\",\"Shop Online\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/\",\"name\":\"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic! - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/demana_online_stick.jpg\",\"datePublished\":\"2021-10-19T11:37:48+00:00\",\"dateModified\":\"2022-01-25T14:29:26+00:00\",\"description\":\"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/demana_online_stick.jpg\",\"contentUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/demana_online_stick.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/pedido-online-pizza-stick-cerdanya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pizzastick.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#website\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/\",\"name\":\"Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\",\"description\":\"Pizzas artesanales de masa fina y crujientes, hechas 100% al momento. Tres pizzer\u00edas para comer en el local o a domicilio: Puigcerd\u00e1, Bellver y Escadarcs.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#organization\"},\"alternateName\":\"Pizza Stick\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pizzastick.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#organization\",\"name\":\"Pizza Stick\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PS_LogoRedondaAmarillo.png\",\"contentUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PS_LogoRedondaAmarillo.png\",\"width\":329,\"height\":329,\"caption\":\"Pizza Stick\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pizzeriapizzastick\",\"https:\\\/\\\/x.com\\\/pizza_stick_\",\"https:\\\/\\\/instagram.com\\\/pizzeriapizzastick\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/person\\\/c164ec506c453162653fb0ffe1c16cce\",\"name\":\"Andrea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce967459384f86ddc3d69942d6e2c92fa06c1ebece9dccf6ef57e404ada6fe0b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce967459384f86ddc3d69942d6e2c92fa06c1ebece9dccf6ef57e404ada6fe0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce967459384f86ddc3d69942d6e2c92fa06c1ebece9dccf6ef57e404ada6fe0b?s=96&d=mm&r=g\",\"caption\":\"Andrea\"},\"sameAs\":[\"https:\\\/\\\/pizzastick.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic! - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","description":"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pizzastick.es\/ca\/pedido-online-pizza-stick-cerdanya\/","og_locale":"ca_ES","og_type":"article","og_title":"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic! - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","og_description":"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.","og_url":"https:\/\/pizzastick.es\/ca\/pedido-online-pizza-stick-cerdanya\/","og_site_name":"Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","article_publisher":"https:\/\/www.facebook.com\/pizzeriapizzastick","article_published_time":"2021-10-19T11:37:48+00:00","article_modified_time":"2022-01-25T14:29:26+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/demana_online_stick.jpg","type":"image\/jpeg"}],"author":"Andrea","twitter_card":"summary_large_image","twitter_creator":"@pizza_stick_","twitter_site":"@pizza_stick_","twitter_misc":{"Escrit per":"Andrea","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#article","isPartOf":{"@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/"},"author":{"name":"Andrea","@id":"https:\/\/pizzastick.es\/#\/schema\/person\/c164ec506c453162653fb0ffe1c16cce"},"headline":"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic!","datePublished":"2021-10-19T11:37:48+00:00","dateModified":"2022-01-25T14:29:26+00:00","mainEntityOfPage":{"@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/"},"wordCount":426,"commentCount":2,"publisher":{"@id":"https:\/\/pizzastick.es\/#organization"},"image":{"@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/demana_online_stick.jpg","keywords":["Cerdanya","Comanda Online","Delivery","Demana Online","Pizzer\u00eda","Shop Online"],"articleSection":["Sin categorizar"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/","url":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/","name":"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic! - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","isPartOf":{"@id":"https:\/\/pizzastick.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#primaryimage"},"image":{"@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/demana_online_stick.jpg","datePublished":"2021-10-19T11:37:48+00:00","dateModified":"2022-01-25T14:29:26+00:00","description":"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.","breadcrumb":{"@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#primaryimage","url":"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/demana_online_stick.jpg","contentUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2021\/10\/demana_online_stick.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/pizzastick.es\/pedido-online-pizza-stick-cerdanya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pizzastick.es\/"},{"@type":"ListItem","position":2,"name":"Activamos el pedido online, \u00a1conecta con nosotros en un solo clic!"}]},{"@type":"WebSite","@id":"https:\/\/pizzastick.es\/#website","url":"https:\/\/pizzastick.es\/","name":"Pizza Stick | Pizzes artesanes per als pizza lovers m\u00e9s exigents","description":"Pizzas artesanales de masa fina y crujientes, hechas 100% al momento. Tres pizzer\u00edas para comer en el local o a domicilio: Puigcerd\u00e1, Bellver y Escadarcs.","publisher":{"@id":"https:\/\/pizzastick.es\/#organization"},"alternateName":"Pizza Stick","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pizzastick.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/pizzastick.es\/#organization","name":"Pizza Stick","url":"https:\/\/pizzastick.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/pizzastick.es\/#\/schema\/logo\/image\/","url":"https:\/\/pizzastick.es\/wp-content\/uploads\/2024\/02\/PS_LogoRedondaAmarillo.png","contentUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2024\/02\/PS_LogoRedondaAmarillo.png","width":329,"height":329,"caption":"Pizza Stick"},"image":{"@id":"https:\/\/pizzastick.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pizzeriapizzastick","https:\/\/x.com\/pizza_stick_","https:\/\/instagram.com\/pizzeriapizzastick\/"]},{"@type":"Person","@id":"https:\/\/pizzastick.es\/#\/schema\/person\/c164ec506c453162653fb0ffe1c16cce","name":"Andrea","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/ce967459384f86ddc3d69942d6e2c92fa06c1ebece9dccf6ef57e404ada6fe0b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce967459384f86ddc3d69942d6e2c92fa06c1ebece9dccf6ef57e404ada6fe0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce967459384f86ddc3d69942d6e2c92fa06c1ebece9dccf6ef57e404ada6fe0b?s=96&d=mm&r=g","caption":"Andrea"},"sameAs":["https:\/\/pizzastick.es"]}]}},"_links":{"self":[{"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/posts\/4231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/comments?post=4231"}],"version-history":[{"count":6,"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/posts\/4231\/revisions"}],"predecessor-version":[{"id":4395,"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/posts\/4231\/revisions\/4395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/media\/4250"}],"wp:attachment":[{"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/media?parent=4231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/categories?post=4231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pizzastick.es\/ca\/wp-json\/wp\/v2\/tags?post=4231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}