{"id":100,"date":"2016-03-03T09:30:11","date_gmt":"2016-03-03T09:30:11","guid":{"rendered":"http:\/\/pizzastick.es\/?p=100"},"modified":"2019-10-31T15:01:54","modified_gmt":"2019-10-31T13:01:54","slug":"estas-a-dieta-pero-te-chifla-la-pizza","status":"publish","type":"post","link":"https:\/\/pizzastick.es\/fr\/estas-a-dieta-pero-te-chifla-la-pizza\/","title":{"rendered":"Vous \u00eates au r\u00e9gime mais vous aimez la pizza ?"},"content":{"rendered":"<p>No es un mix incompatible, todo es posible \u00a1te cuento c\u00f3mo!<\/p>\n<p>No te alarmes. S\u00e9 que tu coraz\u00f3n salta de emoci\u00f3n y a la vez se pregunta: \u00a1\u00bfC\u00f3mo puede ser?!<\/p>\n<p>Creo que en esta vida todo es posible y estoy convencida de que puedes comer tu plato favorito sin que te invada el dichoso sentimiento de culpa.<\/p>\n<p>De verdad, puedes comer tranquilamente y aliviar todo el estr\u00e9s post-vacacional que conlleva la vuelta a la rutina. As\u00ed que una vez en casa, \u00bfNotas c\u00f3mo un poco de caos, otro poco de descontrol y un mucho de falta de tiempo van invadiendo tu mundo y te vienen unas ganas inmensas de volver al para\u00edso de las vacaciones?<\/p>\n<p>Pues <strong>vamos a liberar unas cuantas presiones<\/strong> \u00a1presta atenci\u00f3n! porque en esta vida s\u00ed se puede tener todo y no quiero menos para ti.<\/p>\n<p>Como ya sabes, la dieta mediterr\u00e1nea es una de las m\u00e1s equilibradas. Pues tach\u00e1\u00e1\u00e1\u00e1\u00e1\u00e1n: \u00a1Nuestras pizzas tambi\u00e9n!<\/p>\n<p>Nuestros maestros pizzeros las hacen <strong>cada d\u00eda frescas al momento para ti:<\/strong> \u2018Reci\u00e9n salidas del horno\u2019 y lo m\u00e1s importante: con harina de primera, levadura de cerveza natural, aceite de oliva virgen extra e ingredientes seleccionados uno a uno para que sea un plato sabroso, rico y saludable.<\/p>\n<p>El secreto para que encaje con tu dieta est\u00e1 en elegir bien tus ingredientes al crear la pizza a tu gusto.<\/p>\n<p>Seg\u00fan mi experiencia personal, te cuento que mi nutricionista sab\u00eda que antes de renunciar a mi pizza, yo era capaz de renunciar a mi dieta.<\/p>\n<p>Yo quiero un plan de alimentaci\u00f3n adaptado a mi ritmo de vida: Con ni\u00f1os, casa, perro, deporte y trabajo: \u00a1Un no parar! Deseo que tanto yo como mi familia comamos sano y compartamos <strong>momentos de felicidad distendidos<\/strong>. Y esto, por supuesto, incluye happy-pizza semanal 100% saludable. Acompa\u00f1ado de una alimentaci\u00f3n variada, con mucho color, y sobre todo en movimiento.<\/p>\n<p>\u00a1Y que no me quite el sue\u00f1o por las noches!<\/p>\n<p>Por lo tanto, para los d\u00edas en que no te da tiempo a todo y comprar-cocinar-preparar-limpiar se te hace un mundo que te cae encima como una roca: <strong>la pizza es tu salvaci\u00f3n.<\/strong> Cr\u00e9eme, lo es y lo s\u00e9 de primera mano. Date un respiro y pr\u00e9miate. T\u00fa te lo mereces.<\/p>\n<p>Ten en cuenta estos 5 consejos:<\/p>\n<ol>\n<li>Escoge una ensalada de primero para todos<\/li>\n<li>Comparte una pizza grande (compartir es querer)o si no os pon\u00e9is de acuerdo con los ingredientes, crea tu pizza favorita tama\u00f1o peque\u00f1o.<\/li>\n<li>Elige ingredientes saludables como verduras, at\u00fan, salm\u00f3n, ma\u00edz, espinacas o pimientos.<\/li>\n<li>Evita los ingredientes m\u00e1s grasos como ciertos embutidos\/quesos\/extras.<\/li>\n<li>Haz deporte, salta, baila o corre, libera endorfinas y mejoraras cuerpo y mente.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>As\u00ed tendr\u00e1s tu <strong>plato equilibrado, sano y \u00f1am \u00f1am sin remordimientos y sin esfuerzo.<\/strong><\/p>\n<p>Bye bye \u00a1nos vemos con las manos en la masa!<\/p>\n<p style=\"text-align: center;\">\u00b7<\/p>\n<h3 style=\"text-align: center;\"><strong>P.D. Cu\u00e9ntanos, cu\u00e1l es tu secreto para comer bien sin remordimientos?<\/strong><\/h3>","protected":false},"excerpt":{"rendered":"<p>No es un mix incompatible, todo es posible \u00a1te cuento c\u00f3mo! No te alarmes. S\u00e9 que tu coraz\u00f3n salta de emoci\u00f3n y a la vez se pregunta: \u00a1\u00bfC\u00f3mo puede ser?! Creo que en esta vida todo es posible y estoy convencida de que puedes comer&#8230;<\/p>","protected":false},"author":1,"featured_media":460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEst\u00e1s a dieta pero te chifla la pizza? - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes<\/title>\n<meta name=\"description\" content=\"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pizzastick.es\/fr\/estas-a-dieta-pero-te-chifla-la-pizza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEst\u00e1s a dieta pero te chifla la pizza? - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\" \/>\n<meta property=\"og:description\" content=\"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pizzastick.es\/fr\/estas-a-dieta-pero-te-chifla-la-pizza\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pizzeriapizzastick\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-03T09:30:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-31T13:01:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pizzastick.es\/wp-content\/uploads\/2016\/03\/pizza-stick-blog-imagen-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pizzas Stick Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@andrea_ps\" \/>\n<meta name=\"twitter:site\" content=\"@pizza_stick_\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pizzas Stick Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/\"},\"author\":{\"name\":\"Pizzas Stick Team\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/person\\\/99950d47c4d86baac6b4693adb6b8fbf\"},\"headline\":\"\u00bfEst\u00e1s a dieta pero te chifla la pizza?\",\"datePublished\":\"2016-03-03T09:30:11+00:00\",\"dateModified\":\"2019-10-31T13:01:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/\"},\"wordCount\":520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/pizza-stick-blog-imagen-7.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/\",\"name\":\"\u00bfEst\u00e1s a dieta pero te chifla la pizza? - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/pizza-stick-blog-imagen-7.jpg\",\"datePublished\":\"2016-03-03T09:30:11+00:00\",\"dateModified\":\"2019-10-31T13:01:54+00:00\",\"description\":\"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/pizza-stick-blog-imagen-7.jpg\",\"contentUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/pizza-stick-blog-imagen-7.jpg\",\"width\":1000,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/estas-a-dieta-pero-te-chifla-la-pizza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pizzastick.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEst\u00e1s a dieta pero te chifla la pizza?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#website\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/\",\"name\":\"Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes\",\"description\":\"Pizzas artesanales de masa fina y crujientes, hechas 100% al momento. Tres pizzer\u00edas para comer en el local o a domicilio: Puigcerd\u00e1, Bellver y Escadarcs.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#organization\"},\"alternateName\":\"Pizza Stick\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pizzastick.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#organization\",\"name\":\"Pizza Stick\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PS_LogoRedondaAmarillo.png\",\"contentUrl\":\"https:\\\/\\\/pizzastick.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PS_LogoRedondaAmarillo.png\",\"width\":329,\"height\":329,\"caption\":\"Pizza Stick\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pizzeriapizzastick\",\"https:\\\/\\\/x.com\\\/pizza_stick_\",\"https:\\\/\\\/instagram.com\\\/pizzeriapizzastick\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pizzastick.es\\\/#\\\/schema\\\/person\\\/99950d47c4d86baac6b4693adb6b8fbf\",\"name\":\"Pizzas Stick Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a56b595a8a2b14b019bb33c9a8b441bec4349e50c65ed9e3c1d1bef118082344?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a56b595a8a2b14b019bb33c9a8b441bec4349e50c65ed9e3c1d1bef118082344?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a56b595a8a2b14b019bb33c9a8b441bec4349e50c65ed9e3c1d1bef118082344?s=96&d=mm&r=g\",\"caption\":\"Pizzas Stick Team\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/andrea_ps\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEst\u00e1s a dieta pero te chifla la pizza? - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","description":"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pizzastick.es\/fr\/estas-a-dieta-pero-te-chifla-la-pizza\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfEst\u00e1s a dieta pero te chifla la pizza? - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","og_description":"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.","og_url":"https:\/\/pizzastick.es\/fr\/estas-a-dieta-pero-te-chifla-la-pizza\/","og_site_name":"Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","article_publisher":"https:\/\/www.facebook.com\/pizzeriapizzastick","article_published_time":"2016-03-03T09:30:11+00:00","article_modified_time":"2019-10-31T13:01:54+00:00","og_image":[{"width":1000,"height":600,"url":"https:\/\/pizzastick.es\/wp-content\/uploads\/2016\/03\/pizza-stick-blog-imagen-7.jpg","type":"image\/jpeg"}],"author":"Pizzas Stick Team","twitter_card":"summary_large_image","twitter_creator":"@andrea_ps","twitter_site":"@pizza_stick_","twitter_misc":{"\u00c9crit par":"Pizzas Stick Team","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#article","isPartOf":{"@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/"},"author":{"name":"Pizzas Stick Team","@id":"https:\/\/pizzastick.es\/#\/schema\/person\/99950d47c4d86baac6b4693adb6b8fbf"},"headline":"\u00bfEst\u00e1s a dieta pero te chifla la pizza?","datePublished":"2016-03-03T09:30:11+00:00","dateModified":"2019-10-31T13:01:54+00:00","mainEntityOfPage":{"@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/"},"wordCount":520,"commentCount":0,"publisher":{"@id":"https:\/\/pizzastick.es\/#organization"},"image":{"@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2016\/03\/pizza-stick-blog-imagen-7.jpg","articleSection":["Sin categorizar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/","url":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/","name":"\u00bfEst\u00e1s a dieta pero te chifla la pizza? - Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","isPartOf":{"@id":"https:\/\/pizzastick.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#primaryimage"},"image":{"@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2016\/03\/pizza-stick-blog-imagen-7.jpg","datePublished":"2016-03-03T09:30:11+00:00","dateModified":"2019-10-31T13:01:54+00:00","description":"Pizzas artesanales para los pizzalovers m\u00e1s exigentes. Tres pizzer\u00edas en la comarca de la Cerdanya: Puigcerd\u00e0, Escadarcs, y Bellver de Cerdanya.","breadcrumb":{"@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#primaryimage","url":"https:\/\/pizzastick.es\/wp-content\/uploads\/2016\/03\/pizza-stick-blog-imagen-7.jpg","contentUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2016\/03\/pizza-stick-blog-imagen-7.jpg","width":1000,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/pizzastick.es\/estas-a-dieta-pero-te-chifla-la-pizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pizzastick.es\/"},{"@type":"ListItem","position":2,"name":"\u00bfEst\u00e1s a dieta pero te chifla la pizza?"}]},{"@type":"WebSite","@id":"https:\/\/pizzastick.es\/#website","url":"https:\/\/pizzastick.es\/","name":"Pizza Stick | Pizzas artesanas para los pizza lovers m\u00e1s exigentes","description":"Pizzas artisanales \u00e0 la p\u00e2te fine et croustillante, pr\u00e9par\u00e9es \u00e0 la commande 100%. Trois pizzerias \u00e0 consommer sur place ou \u00e0 domicile : Puigcerd\u00e1, Bellver et Escadarcs.","publisher":{"@id":"https:\/\/pizzastick.es\/#organization"},"alternateName":"Pizza Stick","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pizzastick.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/pizzastick.es\/#organization","name":"B\u00e2ton \u00e0 pizza","url":"https:\/\/pizzastick.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pizzastick.es\/#\/schema\/logo\/image\/","url":"https:\/\/pizzastick.es\/wp-content\/uploads\/2024\/02\/PS_LogoRedondaAmarillo.png","contentUrl":"https:\/\/pizzastick.es\/wp-content\/uploads\/2024\/02\/PS_LogoRedondaAmarillo.png","width":329,"height":329,"caption":"Pizza Stick"},"image":{"@id":"https:\/\/pizzastick.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pizzeriapizzastick","https:\/\/x.com\/pizza_stick_","https:\/\/instagram.com\/pizzeriapizzastick\/"]},{"@type":"Person","@id":"https:\/\/pizzastick.es\/#\/schema\/person\/99950d47c4d86baac6b4693adb6b8fbf","name":"Pizzas Stick Team","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a56b595a8a2b14b019bb33c9a8b441bec4349e50c65ed9e3c1d1bef118082344?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a56b595a8a2b14b019bb33c9a8b441bec4349e50c65ed9e3c1d1bef118082344?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a56b595a8a2b14b019bb33c9a8b441bec4349e50c65ed9e3c1d1bef118082344?s=96&d=mm&r=g","caption":"Pizzas Stick Team"},"sameAs":["https:\/\/x.com\/andrea_ps"]}]}},"_links":{"self":[{"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/posts\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":4,"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/posts\/100\/revisions"}],"predecessor-version":[{"id":2039,"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/posts\/100\/revisions\/2039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/media\/460"}],"wp:attachment":[{"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/media?parent=100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/categories?post=100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pizzastick.es\/fr\/wp-json\/wp\/v2\/tags?post=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}